{"id":208,"date":"2025-01-15T17:38:14","date_gmt":"2025-01-15T16:38:14","guid":{"rendered":"http:\/\/gdpsauveur.fr\/varennes\/?page_id=208"},"modified":"2025-01-15T17:38:16","modified_gmt":"2025-01-15T16:38:16","slug":"gardens","status":"publish","type":"page","link":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/gardens\/","title":{"rendered":"Gardens"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-208","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/pages\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":1,"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/pages\/208\/revisions"}],"predecessor-version":[{"id":209,"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/pages\/208\/revisions\/209"}],"wp:attachment":[{"href":"https:\/\/gdpsauveur.fr\/varennes\/index.php\/wp-json\/wp\/v2\/media?parent=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}